{"id":20293,"date":"2022-12-05T14:29:50","date_gmt":"2022-12-05T13:29:50","guid":{"rendered":"https:\/\/explainvisually.co\/?post_type=project&#038;p=20293"},"modified":"2022-12-05T14:29:50","modified_gmt":"2022-12-05T13:29:50","slug":"illustration-for-salto-3","status":"publish","type":"project","link":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/","title":{"rendered":"Illustration for Salto"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9132 size-full\" src=\"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg\" alt=\"\" width=\"1900\" height=\"1344\" \/><\/figure>\r\n<!-- \/whttps:\/\/explainvisually.co\/wp-admin\/post.php?post=11598&action=edit&lang=pl#p:image -->\r\n\r\n\r\n<div class=\"portfolio-content\">\r\n<div class=\"portfolio-desc\">\r\n<h3>Illustration for Salto<\/h3>\r\n<\/div>\r\n\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Illustration for Salto<\/p>\n","protected":false},"author":2,"featured_media":20279,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"project_category":[90],"project_tag":[],"class_list":["post-20293","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-illustrations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Illustration for Salto - Explain Visually<\/title>\n<meta name=\"description\" content=\"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Illustration for Salto - Explain Visually\" \/>\n<meta property=\"og:description\" content=\"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Explain Visually\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/\",\"url\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/\",\"name\":\"Illustration for Salto - Explain Visually\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explainvisually.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/4-R.-Matei-final-2048x1448-1.jpeg\",\"datePublished\":\"2022-12-05T13:29:50+00:00\",\"description\":\"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explainvisually.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/4-R.-Matei-final-2048x1448-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/explainvisually.co\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/4-R.-Matei-final-2048x1448-1.jpeg\",\"width\":2048,\"height\":1448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/illustration-for-salto-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Illustration for Salto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/\",\"name\":\"Explain Visually\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/explainvisually.co\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Illustration for Salto - Explain Visually","description":"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/","og_locale":"en_US","og_type":"article","og_title":"Illustration for Salto - Explain Visually","og_description":"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!","og_url":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/","og_site_name":"Explain Visually","og_image":[{"width":2048,"height":1448,"url":"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/","url":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/","name":"Illustration for Salto - Explain Visually","isPartOf":{"@id":"https:\/\/explainvisually.co\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/#primaryimage"},"image":{"@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/#primaryimage"},"thumbnailUrl":"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg","datePublished":"2022-12-05T13:29:50+00:00","description":"Illustrations instead of photos of employees can enliven the site, give it character. They can also make a great gift for your team!","breadcrumb":{"@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/#primaryimage","url":"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg","contentUrl":"https:\/\/explainvisually.co\/wp-content\/uploads\/2022\/12\/4-R.-Matei-final-2048x1448-1.jpeg","width":2048,"height":1448},{"@type":"BreadcrumbList","@id":"https:\/\/explainvisually.co\/en\/project\/illustration-for-salto-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/explainvisually.co\/en\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/explainvisually.co\/en\/project\/"},{"@type":"ListItem","position":3,"name":"Illustration for Salto"}]},{"@type":"WebSite","@id":"https:\/\/explainvisually.co\/en\/#website","url":"https:\/\/explainvisually.co\/en\/","name":"Explain Visually","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/explainvisually.co\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project\/20293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/comments?post=20293"}],"version-history":[{"count":1,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project\/20293\/revisions"}],"predecessor-version":[{"id":20294,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project\/20293\/revisions\/20294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/media\/20279"}],"wp:attachment":[{"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/media?parent=20293"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project_category?post=20293"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/explainvisually.co\/en\/wp-json\/wp\/v2\/project_tag?post=20293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}